{"id":5517,"date":"2025-02-13T11:14:46","date_gmt":"2025-02-13T10:14:46","guid":{"rendered":"https:\/\/www.almconsultants.com\/almconsultants\/?page_id=5517"},"modified":"2025-02-27T13:26:49","modified_gmt":"2025-02-27T12:26:49","slug":"politique-de-confidentialite","status":"publish","type":"page","link":"https:\/\/www.almconsultants.com\/almconsultants\/en\/politique-de-confidentialite\/","title":{"rendered":"Politique de confidentialit\u00e9"},"content":{"rendered":"<div style=\"height:24px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center\">Politique de confidentialit\u00e9<\/h1>\n\n\n\n<div style=\"height:24px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-7bed53cf15a9dff39043476ad3006a36\" style=\"color:#cd1d2a\">Qui sommes-nous&nbsp;?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019adresse de notre site est&nbsp;: https:\/\/almconsultants.com<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ALM Consultants<\/strong>\u00a0est un bureau d&rsquo;\u00e9tudes qui s\u2019est donn\u00e9 pour mission d&rsquo;accompagner les entreprises dans leurs d\u00e9marches d\u2019am\u00e9lioration continue des performances. Depuis plus de 20 ans, nous assistons nos clients dans le\u00a0<strong>d\u00e9veloppement, l\u2019organisation et la mise en \u0153uvre de leurs syst\u00e8mes de management<\/strong>\u00a0dans les domaines :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>de la\u00a0<strong>Qualit\u00e9, de l\u2019Environnement, <\/strong><\/li>\n\n\n\n<li>de la<strong> S\u00e9curit\u00e9 des Denr\u00e9es Alimentaires, <\/strong><\/li>\n\n\n\n<li>de la<strong> Sant\u00e9,<\/strong><\/li>\n\n\n\n<li>de la<strong> S\u00e9curit\u00e9 au Travail<\/strong>. <\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Nos prestations incluent\u00a0<strong>les formations inter et intra entreprises, les conseils en organisation et management, les audits et les \u00e9valuations de conformit\u00e9<\/strong>. Les formations que nous proposons s\u2019inscrivent dans une dynamique de progr\u00e8s et d\u2019excellence manag\u00e9riale pour\u00a0<strong>renforces les comp\u00e9tences de votre personnel<\/strong>\u00a0et\u00a0<strong>accro\u00eetre la comp\u00e9titivit\u00e9 de votre entreprise<\/strong>\u00a0dans votre domaine d\u2019activit\u00e9. <\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-a3d7cf95122d60449b538a7f7f3a8852\" style=\"color:#cd1d2a\">Commentaires<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Quand vous laissez un commentaire sur notre site, les donn\u00e9es inscrites dans le formulaire de commentaire, ainsi que votre adresse IP et l\u2019agent utilisateur de votre navigateur sont collect\u00e9s pour nous aider \u00e0 la d\u00e9tection des commentaires ind\u00e9sirables.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une cha\u00eene anonymis\u00e9e cr\u00e9\u00e9e \u00e0 partir de votre adresse e-mail (\u00e9galement appel\u00e9e hash) peut \u00eatre envoy\u00e9e au service Gravatar pour v\u00e9rifier si vous utilisez ce dernier. Les clauses de confidentialit\u00e9 du service Gravatar sont disponibles ici&nbsp;: https:\/\/automattic.com\/privacy\/. Apr\u00e8s validation de votre commentaire, votre photo de profil sera visible publiquement \u00e0 cot\u00e9 de votre commentaire.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-c0133b4a4aff4b4505559f40e1251816\" style=\"color:#cd1d2a\">M\u00e9dias<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous t\u00e9l\u00e9versez des images sur le site, nous vous conseillons d\u2019\u00e9viter de t\u00e9l\u00e9verser des images contenant des donn\u00e9es EXIF de coordonn\u00e9es GPS. Les personnes visitant votre site peuvent t\u00e9l\u00e9charger et extraire des donn\u00e9es de localisation depuis ces images.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-6b9f4a49bd59a91d6c18871267507f84\" style=\"color:#cd1d2a\">Cookies<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous d\u00e9posez un commentaire sur notre site, il vous sera propos\u00e9 d\u2019enregistrer votre nom, adresse e-mail et site dans des cookies. C\u2019est uniquement pour votre confort afin de ne pas avoir \u00e0 saisir ces informations si vous d\u00e9posez un autre commentaire plus tard. Ces cookies expirent au bout d\u2019un an.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous vous rendez sur la page de connexion, un cookie temporaire sera cr\u00e9\u00e9 afin de d\u00e9terminer si votre navigateur accepte les cookies. Il ne contient pas de donn\u00e9es personnelles et sera supprim\u00e9 automatiquement \u00e0 la fermeture de votre navigateur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsque vous vous connecterez, nous mettrons en place un certain nombre de cookies pour enregistrer vos informations de connexion et vos pr\u00e9f\u00e9rences d\u2019\u00e9cran. La dur\u00e9e de vie d\u2019un cookie de connexion est de deux jours, celle d\u2019un cookie d\u2019option d\u2019\u00e9cran est d\u2019un an. Si vous cochez \u00ab&nbsp;Se souvenir de moi&nbsp;\u00bb, votre cookie de connexion sera conserv\u00e9 pendant deux semaines. Si vous vous d\u00e9connectez de votre compte, le cookie de connexion sera effac\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En modifiant ou en publiant une publication, un cookie suppl\u00e9mentaire sera enregistr\u00e9 dans votre navigateur. Ce cookie ne comprend aucune donn\u00e9e personnelle. Il indique simplement l\u2019ID de la publication que vous venez de modifier. Il expire au bout d\u2019un jour.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-17c1cacfb86e037bcb2d1e7d96b1b658\" style=\"color:#cd1d2a\">Contenu embarqu\u00e9 depuis d\u2019autres sites<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les articles de ce site peuvent inclure des contenus int\u00e9gr\u00e9s (par exemple des vid\u00e9os, images, articles\u2026). Le contenu int\u00e9gr\u00e9 depuis d\u2019autres sites se comporte de la m\u00eame mani\u00e8re que si le visiteur se rendait sur cet autre site.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ces sites web pourraient collecter des donn\u00e9es sur vous, utiliser des cookies, embarquer des outils de suivis tiers, suivre vos interactions avec ces contenus embarqu\u00e9s si vous disposez d\u2019un compte connect\u00e9 sur leur site web.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-979f7eb98a2c7ccd4a70c4e3a9461c1c\" style=\"color:#cd1d2a\">Utilisation et transmission de vos donn\u00e9es personnelles<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous demandez une r\u00e9initialisation de votre mot de passe, votre adresse IP sera incluse dans l\u2019e-mail de r\u00e9initialisation.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-e62b20d935e059d9e90666a199b1db71\" style=\"color:#cd1d2a\">Dur\u00e9es de stockage de vos donn\u00e9es<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous laissez un commentaire, le commentaire et ses m\u00e9tadonn\u00e9es sont conserv\u00e9s ind\u00e9finiment. Cela permet de reconna\u00eetre et approuver automatiquement les commentaires suivants au lieu de les laisser dans la file de mod\u00e9ration.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour les comptes qui s\u2019inscrivent sur notre site (le cas \u00e9ch\u00e9ant), nous stockons \u00e9galement les donn\u00e9es personnelles indiqu\u00e9es dans leur profil. Tous les comptes peuvent voir, modifier ou supprimer leurs informations personnelles \u00e0 tout moment (\u00e0 l\u2019exception de leur identifiant). Les gestionnaires du site peuvent aussi voir et modifier ces informations.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-c2014396f9c8d0c4d71397afcfad3725\" style=\"color:#cd1d2a\">Les droits que vous avez sur vos donn\u00e9es<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous avez un compte ou si vous avez laiss\u00e9 des commentaires sur le site, vous pouvez demander \u00e0 recevoir un fichier contenant toutes les donn\u00e9es personnelles que nous poss\u00e9dons \u00e0 votre sujet, incluant celles que vous nous avez fournies. Vous pouvez \u00e9galement demander la suppression des donn\u00e9es personnelles vous concernant. Cela ne prend pas en compte les donn\u00e9es stock\u00e9es \u00e0 des fins administratives, l\u00e9gales ou pour des raisons de s\u00e9curit\u00e9.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-641ecdd724f16f86aab91e0bb65f7792\" style=\"color:#cd1d2a\">O\u00f9 vos donn\u00e9es sont envoy\u00e9es<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les commentaires des visiteurs peuvent \u00eatre v\u00e9rifi\u00e9s \u00e0 l\u2019aide d\u2019un service automatis\u00e9 de d\u00e9tection des commentaires ind\u00e9sirables.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Politique de confidentialit\u00e9 Qui sommes-nous&nbsp;? L\u2019adresse de notre site est&nbsp;: https:\/\/almconsultants.com ALM Consultants\u00a0est un bureau d&rsquo;\u00e9tudes qui s\u2019est donn\u00e9 pour mission d&rsquo;accompagner les entreprises dans leurs d\u00e9marches d\u2019am\u00e9lioration continue des performances. Depuis plus de 20 ans, nous assistons nos clients dans le\u00a0d\u00e9veloppement, l\u2019organisation et la mise en \u0153uvre de leurs syst\u00e8mes de management\u00a0dans les domaines [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"qubely_global_settings":"","qubely_interactions":"","content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-5517","page","type-page","status-publish","hentry"],"blocksy_meta":[],"_links":{"self":[{"href":"https:\/\/www.almconsultants.com\/almconsultants\/en\/wp-json\/wp\/v2\/pages\/5517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.almconsultants.com\/almconsultants\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.almconsultants.com\/almconsultants\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.almconsultants.com\/almconsultants\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.almconsultants.com\/almconsultants\/en\/wp-json\/wp\/v2\/comments?post=5517"}],"version-history":[{"count":10,"href":"https:\/\/www.almconsultants.com\/almconsultants\/en\/wp-json\/wp\/v2\/pages\/5517\/revisions"}],"predecessor-version":[{"id":5823,"href":"https:\/\/www.almconsultants.com\/almconsultants\/en\/wp-json\/wp\/v2\/pages\/5517\/revisions\/5823"}],"wp:attachment":[{"href":"https:\/\/www.almconsultants.com\/almconsultants\/en\/wp-json\/wp\/v2\/media?parent=5517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}